{"id":79,"date":"2013-05-29T10:28:01","date_gmt":"2013-05-29T10:28:01","guid":{"rendered":"http:\/\/fissazionecentrale.it\/wordpress\/?p=79"},"modified":"2013-05-29T10:28:01","modified_gmt":"2013-05-29T10:28:01","slug":"metodo-bates-per-la-vistamal-di-testa","status":"publish","type":"post","link":"http:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/","title":{"rendered":"Metodo Bates per la vista\/mal di testa"},"content":{"rendered":"<p>Interessante articolo da un blog (http:\/\/menopausaprecoce.forumfree.it\/?t=33595083) :<\/p>\n<p>Ciao a tutte.<\/p>\n<p>Vi racconto il seguente fatto, che credo potrebbe risolvere il problema a tante donne che prendono ormoni, poich\u00e8 uno degli effetti collaterali \u00e8 appunto il mal di testa.<br \/>\nCirca un anno fa ho cambiato pillola ormonale e da quel momento ho avventito che spesso alla sera avevo delle forti emicranie. Poich\u00e8 dal bugiardino di questi farmaci \u00e8 riportato che possono provocare il mal di testa, ho pensato bene di sopsendere per un periodo di un mese il farmaco.<\/p>\n<p>Nonostante cio i dolori continuavano, anche se meno forti. Successivamente per un caso della fortuna, mi sono imbattuta in un sito che parlava del metodo bates.<\/p>\n<p>C&#8217;\u00e8 da premettere che sono piu di dieci anni che porto gli occhiali e a quel tempo avevo 7 diottire di miopia. Ebbene, sono venuta a conoscenza che dalla miopia e da tutti gli altri errori di rifrazione \u00e8 possibile guarire del tutto e permanetemente ed inoltre (la cosa assolutamente scoccante per me poich\u00e8 non ne ero a conoscenza) portare li occhiali e le lenti a contatto \u00e8 assolutament dannoso poich\u00e8 tali strumenti sono stati studiati apposta per far peggiorare drasticamente la vista, rendendo l&#8217;occhio totalmente dipendente da essi e per fare in modo che chi porta gli occhiali abbia la necessit\u00e0 di cambiarne un paio almeno ogni 2 anni, per poter permettere all&#8217;industria delle lenti di produrre. Uno degli effetti collaterali delle lenti \u00e8 il mal di testa ed esso puo venire ampilificato se si usano farmaci ai quali si \u00e8 sensibili da questo punto di vista, e se vengono indossate per decenni in alcune persone portano alla cecit\u00e0.<\/p>\n<p>Oltre il mal di testa da lenti, esiste il mal di testa da sforzo oculare, che puo riguardare anche persone a cui non sono mai stati prescritti gli occhiali. Infatti, tutti gli errori di rifrazione sono dovuti ad uno sforzo per vedere, che coinvolge in maniere differenti i muscoli extraoculari (gli erecti e gli obliqui) che inducono l&#8217;occhio a cambiare la sua forma, da rotonda (occhio emmetrope) a allungata (occhio miope) a schiacchiata avanti e dientro (occhio ipermetrope). A seguito di queste deformazioni, i raggi luminosi non si mettono a fuoco su un punto, ma su area piu o meno ampia a seconda delle&#8217;errore di rifrazione.<\/p>\n<p>Chi come me \u00e8 affetto da questa patologia sappia che deve assolutamente togliersi gli occhiali e non metterli su mai piu per nessun motivo e di iniziare a fare la cura di bates, soprattutto se soffre di emicranie da pillola come soffrivo io. Infatti, dopo quasi un anno di trattamento, togliendo da subito gli occhiali, ho recuperato 5 diottrie e i mal di testa sono spariti quasisubito dopo l&#8217;eliminazione degli occhiali. Ho quindi ripreso ad assumnere la pillola.<\/p>\n<p>Ho ritenuto opportuno mettere questo topic vista la mia esperienza andata veramente a buon fine. Non so se questo fatto qualuna di voi gia lo conosceva; tuttavia, so per certo che la stragrande maggioranza delle perosne questo fatto non lo sa. Per esempio, non tutti sanno che l&#8217;occhio normale non gode di vista perfetta permanentemente e che gli errori di rifrazione sono estremamente variabili in senso positivo che in negativo e da questi fatti scentificamenti dismostrati, si evince che l&#8217;uso degli occhiali \u00e8 assoltamente inutile, oltre che dannoso (il 99% delle prsone crede che gli occhiali indossati da una persona emmetrope siano assolutamente dannosi, mentre se indossati da una persona con errori di rifrazione, non sono dannosi, ma necessari. NIENTE DI PIU SBAGLIATO!!!!!!!!!! Gli occhiali sono solo un rimedio messo alla bell&#8217;e meglio per tamponare il problema, ma NON SONO LA CURA. La cosa che mi fa rabbia e che mi s convolge all&#8217;ennesima potenza e che gli oculisti sanno tutto e se stanno zitti, almeno per quanto rigurda la stragrande maggioranza della categoria. Infatti, molti di loro hanno un negozio o fabbrica di ottica. Capiamoci&#8230;<\/p>\n<p>Per questo e altri motivi ho smesso di credere a tutti i dottori, che mi offrono non una cura, ma un tamponamento alla bell&#8217;e meglio, come la pillola. Infatti, cosa far\u00f2 quando il mio corpo non la potr\u00e0 piu accettare o mi beccher\u00f2 un tumore alla mammella o al collon dell&#8217;utero?? Dovr\u00f2 stare senza ormoni? Dvr\u00f2 ricominciare un&#8217;altra volta con le chemioterapie e con tutte le sofferenze che mi \u00e8 toccato patire? Per questo ho deciso di arrangiarmi a trovarmi un cura da sola come ho fatto con gli occhi. Se avessi ascoltato l&#8217;oculista oggi avrei 8 diottrie, invece di 7 di miopia, mentre dopo quasi un anno di cura, tra alti e bassi, ho recuperato 5 diottrie e me ne mancano solo 2 e perdipiu non ho piu mal di testa!!!!!!!!<\/p>\n<p>Quindi, ora che siete a conoscenza di questa verit\u00e0 e che sapete che la maggior parte delle volte il mal di testa \u00e8 provocato dagli occhiali e dallo sforzo oculare, chi volesse approfondire l&#8217;argomento o iniziare senza rischi ne controindicazioni la cura verso la gurigione delle emicranie e degli errori di rifrazione, gli lascio il link dove sono andata a prendere le informazioni:<\/p>\n<p>metodobates.altervista.org<\/p>\n<p>PS1: chi avesse bisogno di una mano su questo argomento o volesse confrontarsi con altre persone che praticano il metodo c&#8217;\u00e8 il GRUPPO METODO BATES oppure, visto il mio successo, potete contattarmi liberamente per consigli alla mia email &#8230;<\/p>\n<p>PS2: Se con questo argomento ho involontariamente messo qualche oculista, iscritta al forum, a disagio, chiedo scusa, e gli consiglio vivamente di avviare questa pratica nel suo studio se non lo ha ancora fatto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interessante articolo da un blog (http:\/\/menopausaprecoce.forumfree.it\/?t=33595083) : Ciao a tutte. Vi racconto il seguente fatto, che credo potrebbe risolvere il problema a tante donne che prendono ormoni, poich\u00e8 uno degli effetti collaterali \u00e8 appunto il mal di testa. Circa un anno fa ho cambiato pillola ormonale e da quel momento ho avventito che spesso alla &hellip; <a href=\"http:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Metodo Bates per la vista\/mal di testa&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-79","post","type-post","status-publish","format-gallery","hentry","category-generale","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metodo Bates per la vista\/mal di testa - fissazionecentrale blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metodo Bates per la vista\/mal di testa - fissazionecentrale blog\" \/>\n<meta property=\"og:description\" content=\"Interessante articolo da un blog (http:\/\/menopausaprecoce.forumfree.it\/?t=33595083) : Ciao a tutte. Vi racconto il seguente fatto, che credo potrebbe risolvere il problema a tante donne che prendono ormoni, poich\u00e8 uno degli effetti collaterali \u00e8 appunto il mal di testa. Circa un anno fa ho cambiato pillola ormonale e da quel momento ho avventito che spesso alla &hellip; Leggi tutto &quot;Metodo Bates per la vista\/mal di testa&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/\" \/>\n<meta property=\"og:site_name\" content=\"fissazionecentrale blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-29T10:28:01+00:00\" \/>\n<meta name=\"author\" content=\"sky\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sky\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/\"},\"author\":{\"name\":\"sky\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\"},\"headline\":\"Metodo Bates per la vista\\\/mal di testa\",\"datePublished\":\"2013-05-29T10:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/\"},\"wordCount\":921,\"commentCount\":0,\"articleSection\":[\"Generale\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/\",\"url\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/\",\"name\":\"Metodo Bates per la vista\\\/mal di testa - fissazionecentrale blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#website\"},\"datePublished\":\"2013-05-29T10:28:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/metodo-bates-per-la-vistamal-di-testa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metodo Bates per la vista\\\/mal di testa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/\",\"name\":\"fissazionecentrale blog\",\"description\":\"Il metodo Bates per il trattamento dei problemi della vista.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\",\"name\":\"sky\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"caption\":\"sky\"},\"sameAs\":[\"http:\\\/\\\/www.fissazionecentrale.it\"],\"url\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/author\\\/sky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metodo Bates per la vista\/mal di testa - fissazionecentrale blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/","og_locale":"it_IT","og_type":"article","og_title":"Metodo Bates per la vista\/mal di testa - fissazionecentrale blog","og_description":"Interessante articolo da un blog (http:\/\/menopausaprecoce.forumfree.it\/?t=33595083) : Ciao a tutte. Vi racconto il seguente fatto, che credo potrebbe risolvere il problema a tante donne che prendono ormoni, poich\u00e8 uno degli effetti collaterali \u00e8 appunto il mal di testa. Circa un anno fa ho cambiato pillola ormonale e da quel momento ho avventito che spesso alla &hellip; Leggi tutto \"Metodo Bates per la vista\/mal di testa\"","og_url":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/","og_site_name":"fissazionecentrale blog","article_published_time":"2013-05-29T10:28:01+00:00","author":"sky","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"sky","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/#article","isPartOf":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/"},"author":{"name":"sky","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be"},"headline":"Metodo Bates per la vista\/mal di testa","datePublished":"2013-05-29T10:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/"},"wordCount":921,"commentCount":0,"articleSection":["Generale"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/","url":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/","name":"Metodo Bates per la vista\/mal di testa - fissazionecentrale blog","isPartOf":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/#website"},"datePublished":"2013-05-29T10:28:01+00:00","author":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be"},"breadcrumb":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fissazionecentrale.it\/wordpress\/metodo-bates-per-la-vistamal-di-testa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fissazionecentrale.it\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Metodo Bates per la vista\/mal di testa"}]},{"@type":"WebSite","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#website","url":"https:\/\/fissazionecentrale.it\/wordpress\/","name":"fissazionecentrale blog","description":"Il metodo Bates per il trattamento dei problemi della vista.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fissazionecentrale.it\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be","name":"sky","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","caption":"sky"},"sameAs":["http:\/\/www.fissazionecentrale.it"],"url":"http:\/\/fissazionecentrale.it\/wordpress\/author\/sky\/"}]}},"_links":{"self":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":0,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"wp:attachment":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}