{"id":59,"date":"2013-02-18T08:59:53","date_gmt":"2013-02-18T08:59:53","guid":{"rendered":"http:\/\/fissazionecentrale.it\/wordpress\/?p=59"},"modified":"2013-04-18T09:00:29","modified_gmt":"2013-04-18T09:00:29","slug":"59","status":"publish","type":"post","link":"http:\/\/fissazionecentrale.it\/wordpress\/59\/","title":{"rendered":"Geni della miopia?"},"content":{"rendered":"<h5 data-ft=\"{&quot;type&quot;:1,&quot;tn&quot;:&quot;K&quot;}\">Agenzia di Stampa.<\/h5>\n<h5 data-ft=\"{&quot;type&quot;:1,&quot;tn&quot;:&quot;K&quot;}\">Geni della miopia? Ci mancava questa!<br \/>\nCredo che si possa essere predisposti, anche comportamentalmente, ma che dipenda comunque tutto da come si finisce a impara ad usare l&#8217;occhio, conseguenza, come spiega Bates, di come viene impostato il sistema visivo&#8230;<br \/>\nNon a caso in oriente la miopia \u00e8 pi\u00f9 diffusa: leggere un ideogramma &#8220;invita&#8221; molto alla diffusione (il contrario della fissazione centrale o centralizzazione). Lo stesso dicasi per la lettura della musica, anche li la &#8220;tentazione&#8221; di diffondere \u00e8 pi\u00f9 alta&#8230;<br \/>\nGiro per &#8220;Nice to Know&#8221; (ma sono in disaccordo)<\/h5>\n<h5 data-ft=\"{&quot;type&quot;:1,&quot;tn&quot;:&quot;K&quot;}\">Vista: scoperti i geni della miopia<br \/>\nLondra, 11 feb. &#8211; Scoperti i geni della &#8220;vista corta&#8221;. Un team internazionale di scienziati, coordinato dal King&#8217;s college di Londra, ha identificato ventiquattro nuovi geni responsabili della miopia. Lo studio e&#8217; stato descritto sulla rivista Nature Genetics ed ha svelato le cause genetiche del diffuso disturbo della vista. Un traguardo, questo, che potrebbe portare alla creazione di trattamenti migliori o di strategie di prevenzione di questa condizione in futuro. La miopia riguarda il trenta per cento della popolazione occidentale e l&#8217;ottanta per cento delle popolazioni asiatiche. Per trovare i geni responsabili della &#8220;vista corta&#8221;, ricercatori europei, asiatici, australiani e statunitensi hanno collaborato all&#8217;interno del Consortium for Refraction and Myopia (CREAM). Ed hanno analizzato i dati genetici relativi alla miopia di quarantacinquemila persone prodotti da trentadue studi differenti. Risultato? L&#8217;identificazione di ventiquattro nuovi geni per lo sviluppo della miopia e la conferma del coinvolgimento di due geni precedentemente rilevati. Il gruppo di geni ne include alcuni collegati alle funzioni cerebrali, al tessuto oculare di segnalazione, alla struttura e allo sviluppo dell&#8217;occhio. La ricerca si intitola &#8220;Genome-wide meta-analyses of multiancestry cohorts identify multiple new susceptibility loci for refractive error and myopia&#8221;.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Agenzia di Stampa. Geni della miopia? Ci mancava questa! Credo che si possa essere predisposti, anche comportamentalmente, ma che dipenda comunque tutto da come si finisce a impara ad usare l&#8217;occhio, conseguenza, come spiega Bates, di come viene impostato il sistema visivo&#8230; Non a caso in oriente la miopia \u00e8 pi\u00f9 diffusa: leggere un ideogramma &hellip; <a href=\"http:\/\/fissazionecentrale.it\/wordpress\/59\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Geni della miopia?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":61,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-59","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-generale","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geni della miopia? - fissazionecentrale blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/fissazionecentrale.it\/wordpress\/59\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geni della miopia? - fissazionecentrale blog\" \/>\n<meta property=\"og:description\" content=\"Agenzia di Stampa. Geni della miopia? Ci mancava questa! Credo che si possa essere predisposti, anche comportamentalmente, ma che dipenda comunque tutto da come si finisce a impara ad usare l&#8217;occhio, conseguenza, come spiega Bates, di come viene impostato il sistema visivo&#8230; Non a caso in oriente la miopia \u00e8 pi\u00f9 diffusa: leggere un ideogramma &hellip; Leggi tutto &quot;Geni della miopia?&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/fissazionecentrale.it\/wordpress\/59\/\" \/>\n<meta property=\"og:site_name\" content=\"fissazionecentrale blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-18T08:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-18T09:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"336\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sky\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sky\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/\"},\"author\":{\"name\":\"sky\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\"},\"headline\":\"Geni della miopia?\",\"datePublished\":\"2013-02-18T08:59:53+00:00\",\"dateModified\":\"2013-04-18T09:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/\"},\"wordCount\":294,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/occhio_muscoli.jpg\",\"articleSection\":[\"Generale\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/\",\"url\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/\",\"name\":\"Geni della miopia? - fissazionecentrale blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/occhio_muscoli.jpg\",\"datePublished\":\"2013-02-18T08:59:53+00:00\",\"dateModified\":\"2013-04-18T09:00:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#primaryimage\",\"url\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/occhio_muscoli.jpg\",\"contentUrl\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/occhio_muscoli.jpg\",\"width\":336,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/59\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geni della miopia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/\",\"name\":\"fissazionecentrale blog\",\"description\":\"Il metodo Bates per il trattamento dei problemi della vista.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/#\\\/schema\\\/person\\\/76aa5d8c14772c8ab511a191271373be\",\"name\":\"sky\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g\",\"caption\":\"sky\"},\"sameAs\":[\"http:\\\/\\\/www.fissazionecentrale.it\"],\"url\":\"http:\\\/\\\/fissazionecentrale.it\\\/wordpress\\\/author\\\/sky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geni della miopia? - fissazionecentrale blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/fissazionecentrale.it\/wordpress\/59\/","og_locale":"it_IT","og_type":"article","og_title":"Geni della miopia? - fissazionecentrale blog","og_description":"Agenzia di Stampa. Geni della miopia? Ci mancava questa! Credo che si possa essere predisposti, anche comportamentalmente, ma che dipenda comunque tutto da come si finisce a impara ad usare l&#8217;occhio, conseguenza, come spiega Bates, di come viene impostato il sistema visivo&#8230; Non a caso in oriente la miopia \u00e8 pi\u00f9 diffusa: leggere un ideogramma &hellip; Leggi tutto \"Geni della miopia?\"","og_url":"http:\/\/fissazionecentrale.it\/wordpress\/59\/","og_site_name":"fissazionecentrale blog","article_published_time":"2013-02-18T08:59:53+00:00","article_modified_time":"2013-04-18T09:00:29+00:00","og_image":[{"width":336,"height":280,"url":"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg","type":"image\/jpeg"}],"author":"sky","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"sky","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#article","isPartOf":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/"},"author":{"name":"sky","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be"},"headline":"Geni della miopia?","datePublished":"2013-02-18T08:59:53+00:00","dateModified":"2013-04-18T09:00:29+00:00","mainEntityOfPage":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/"},"wordCount":294,"commentCount":0,"image":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#primaryimage"},"thumbnailUrl":"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg","articleSection":["Generale"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/fissazionecentrale.it\/wordpress\/59\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/","url":"http:\/\/fissazionecentrale.it\/wordpress\/59\/","name":"Geni della miopia? - fissazionecentrale blog","isPartOf":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/#website"},"primaryImageOfPage":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#primaryimage"},"image":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#primaryimage"},"thumbnailUrl":"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg","datePublished":"2013-02-18T08:59:53+00:00","dateModified":"2013-04-18T09:00:29+00:00","author":{"@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be"},"breadcrumb":{"@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/fissazionecentrale.it\/wordpress\/59\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#primaryimage","url":"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg","contentUrl":"http:\/\/fissazionecentrale.it\/wordpress\/wp-content\/uploads\/2013\/04\/occhio_muscoli.jpg","width":336,"height":280},{"@type":"BreadcrumbList","@id":"http:\/\/fissazionecentrale.it\/wordpress\/59\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fissazionecentrale.it\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Geni della miopia?"}]},{"@type":"WebSite","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#website","url":"https:\/\/fissazionecentrale.it\/wordpress\/","name":"fissazionecentrale blog","description":"Il metodo Bates per il trattamento dei problemi della vista.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fissazionecentrale.it\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/fissazionecentrale.it\/wordpress\/#\/schema\/person\/76aa5d8c14772c8ab511a191271373be","name":"sky","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7425c4853bc200ec7acf7e997ef251233de42e92cb1d37c32d22932d65327a33?s=96&d=mm&r=g","caption":"sky"},"sameAs":["http:\/\/www.fissazionecentrale.it"],"url":"http:\/\/fissazionecentrale.it\/wordpress\/author\/sky\/"}]}},"_links":{"self":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":0,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/posts\/59\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/categories?post=59"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fissazionecentrale.it\/wordpress\/wp-json\/wp\/v2\/tags?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}